{"id":235989,"date":"2022-11-09T10:47:26","date_gmt":"2022-11-09T09:47:26","guid":{"rendered":"https:\/\/het-filter.de\/atex-gli-indicatori-di-esplosione-piu-importanti-in-un-colpo-docchio\/"},"modified":"2025-04-02T11:20:54","modified_gmt":"2025-04-02T09:20:54","slug":"atex-gli-indicatori-di-esplosione-piu-importanti-in-un-colpo-docchio","status":"publish","type":"post","link":"https:\/\/het-filter.de\/it\/atex-gli-indicatori-di-esplosione-piu-importanti-in-un-colpo-docchio\/","title":{"rendered":"ATEX: gli indicatori di esplosione pi\u00f9 importanti in un colpo d&#8217;occhio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Come si verificano le esplosioni? Che cosa comporta? Come si pu\u00f2 valutare il pericolo e infine evitarlo? Queste domande sorgono quando, ad esempio, si possono formare miscele esplosive a causa della presenza di polveri.   <\/p>\n\n<p class=\"wp-block-paragraph\">Un\u2019esplosione pu\u00f2 verificarsi quando una sostanza combustibile in concentrazione sufficiente entra in contatto con un agente ossidante (ad esempio l\u2019aria) in presenza di una fonte di accensione.\nIl rischio di un\u2019esplosione di polvere non deve essere sottovalutato, soprattutto nelle aree industriali in cui si producono polveri sottili come quelle di legno, metallo o organiche. <\/p>\n\n<p class=\"wp-block-paragraph\">La valutazione e la prevenzione dei rischi di esplosione si basano essenzialmente sulla conoscenza delle caratteristiche di esplosione, che descrivono le propriet\u00e0 di una sostanza in relazione alla sua esplosivit\u00e0. Questi indicatori includono il limite inferiore di esplosione (LEL), il limite superiore di esplosione (UEL), la temperatura di accensione, l\u2019energia minima di accensione e la pressione massima di esplosione. <\/p>\n\n<h2 class=\"wp-block-heading h2-blog\" id=\"h-wie-entstehen-explosionen\">Come si verificano le esplosioni?<\/h2>\n\n<p class=\"wp-block-paragraph\">Quando si parla di ATEX, vengono utilizzati sempre gli stessi termini. Per avere una visione d\u2019insieme dell\u2019argomento, \u00e8 necessario chiarire questi termini. <\/p>\n\n<p class=\"wp-block-paragraph\">Una breve panoramica dei termini e del loro significato:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>ATEX<\/strong>: ATmosph\u00e8res EXplosibles = atmosfere esplosive<\/li>\n\n\n\n<li><strong>Sostanze esplosive<\/strong>: sostanze o miscele solide, liquide, pastose e gelatinose che possono essere esplosive in assenza di ossigeno nell\u2019aria.<\/li>\n\n\n\n<li><strong>Miscela esplosiva\/atmosfera esplosiva<\/strong>: Miscela di gas, vapori, nebbie o polveri infiammabili con aria o altri agenti ossidanti.<\/li>\n\n\n\n<li><strong>Esplosione<\/strong>: aumento improvviso di pressione e\/o temperatura<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading h2-blog\" id=\"h-wichtige-explosionskennzahlen-zum-thema-atex\">Importanti indicatori di esplosione in tema di ATEX<\/h2>\n\n<p class=\"wp-block-paragraph\">I parametri relativi alla sicurezza descrivono le propriet\u00e0 di incendio ed esplosione di una sostanza. Dipendono dalle condizioni ambientali, dal metodo di determinazione e dalla sostanza stessa. <\/p>\n\n<p class=\"wp-block-paragraph\">Le cifre chiave dell\u2019esplosione possono essere utilizzate per calcolare le misure di protezione adeguate e i dispositivi di protezione necessari e selezionarli in base all\u2019uso previsto. Inoltre, queste cifre chiave costituiscono la base per la creazione di valutazioni del rischio (documento di protezione dalle esplosioni) o per la selezione di zone Ex. <\/p>\n\n<p class=\"wp-block-paragraph\">I dati pi\u00f9 importanti relativi alle polveri sono riportati di seguito come panoramica pratica:<\/p>\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<table id=\"tablepress-6\" class=\"tablepress tablepress-id-6\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><br \/>\nExplosionskennzahl<\/th><th class=\"column-2\">Bedeutung<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Brennzahl BZ<\/td><td class=\"column-2\">Kenngr\u00f6\u00dfe f\u00fcr das Brandverhalten von Feststoffen. Erfahrungsgem\u00e4\u00df nimmt die Brandausbreitung bei Stoffen, die bei  Raumtemperatur nur ein schwaches Abbrandverhalten zeigen, mit steigender Temperatur zu, d. h. die Brennzahl wird h\u00f6her.<br \/>\n1 -> kein Anbrennen, z. B. Salz<br \/>\n2 -> kurzes Anbrennen, z. B. Malz<br \/>\n3 -> l\u00e4ngeres \u00f6rtliches Glimmen\/Brennen, z.B. Lactose<br \/>\n4 -> Ausbreitung eines Glimmbrands, z. B. Tabak<br \/>\n5 -> Ausbreitung eines offenen Brands, z. B. Schwefel<br \/>\n6 -> verpuffungsartiges Abbrennen, z. B Schwarzpulver<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Glimmtemperatur [\u00b0C]<\/td><td class=\"column-2\">Kenngr\u00f6\u00dfe f\u00fcr die Z\u00fcndtemperatur einer Staubschicht: Unter Versuchsbedingungen ermittelte niedrigste Temperatur einer hei\u00dfen Oberfl\u00e4che, bei der sich eine Staubschicht von 5 mm Dicke entz\u00fcndet.<br \/>\nMit Zunahme der Schichtdicke des Staubs sinkt die<br \/>\nGlimmtemperatur.<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Explosionsdruck Pmax [bar]<\/td><td class=\"column-2\">H\u00f6chster Druckwert eines Staub-\/Luftgemisches in einem geschlossenen Beh\u00e4lter bei einer Explosion.<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Explosionsgruppe III<\/td><td class=\"column-2\">Einteilung von St\u00e4uben anhand ihrer spezifischen<br \/>\nZ\u00fcndf\u00e4higkeit, Unterscheidung nach Eigenschaften:<br \/>\nIIIA (brennbare Flusen), z.B. Flock<br \/>\nIIIB (nicht leitf\u00e4higer Staub), z.B. Pulverlack<br \/>\nIIIC (leitf\u00e4higer Staub), z.B. Metallstaub<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Mindestz\u00fcndenergie<br \/>\nMZE [mJ]<\/td><td class=\"column-2\">Unter vorgeschriebenen Versuchsbedingungen<br \/>\n(atmosph\u00e4rischer Druck, 20\u00b0C) ermittelte, kleinste<br \/>\nEnergie, die ausreicht, die z\u00fcndwilligste explosionsf\u00e4hige<br \/>\nAtmosph\u00e4re zu entz\u00fcnden. (EN 13237)<br \/>\nMZE > 10.000 mJ nicht entz\u00fcndlich<br \/>\nMZE 10 - 10.000 mJ normal entz\u00fcndlich<br \/>\nMZE 3 - 10 mJ besonders entz\u00fcndlich<br \/>\nMZE < 3 mJ extrem entz\u00fcndlich<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Explosionskonstante<br \/>\nK\/KST-Wert [bar *m\/s]<\/td><td class=\"column-2\">Klassifizierungswert, der die Brisanz einer Verbrennung<br \/>\nausdr\u00fcckt. Er entspricht zahlenm\u00e4\u00dfig dem Wert f\u00fcr die maximale Druckanstiegsgeschwindigkeit bei einer Explosion eines Staub\/Luft-Gemisches in einem 1 m\u00b3-Beh\u00e4lter.<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Staubexplosionsklasse<\/td><td class=\"column-2\">Ausdruck der Explosionsf\u00e4higkeit<br \/>\nSt 1 KST - Wert: < 200<br \/>\nSt 2 KST - Wert: 200 - 300<br \/>\nSt 3 KST - Wert: > 300<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Sauerstoffgrenzkonzentration SGK [Vol%]<\/td><td class=\"column-2\">Wert f\u00fcr die h\u00f6chste Sauerstoffkonzentration in<br \/>\neinem Gemisch aus Luft, Inertgas und Gas, bei der<br \/>\nkeine Explosion m\u00f6glich ist. Wird die SGK unterschritten, ist es nicht mehr m\u00f6glich, eine Explosion einzuleiten (zu wenig Sauerstoff vorhanden).<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Selbstentz\u00fcndung<\/td><td class=\"column-2\">Entz\u00fcndung einer Staubsch\u00fcttung bei allseitiger W\u00e4rmeeinwirkung und Anwesenheit von Luft nach vorangegangener Selbsterhitzung.<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Selbstentz\u00fcndungstemperatur<br \/>\n[\u00b0C]<\/td><td class=\"column-2\">Temperatur, bei der bei Staub Selbstentz\u00fcndung<br \/>\nauftritt. Diese ist abh\u00e4ngig von Staubart, Form und<br \/>\nGr\u00f6\u00dfe der Sch\u00fcttung sowie Dauer der W\u00e4rmeeinwirkung.<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Partikelgr\u00f6\u00dfe\/Korngr\u00f6\u00dfe [\u03bcm]<\/td><td class=\"column-2\">Gr\u00f6\u00dfe der Partikel, Angabe \u00fcber den Median (50%<br \/>\nsind gr\u00f6\u00dfer und 50% sind kleiner als dieser Wert). Kennzahl f\u00fcr die Z\u00fcndf\u00e4higkeit des Staubes.<br \/>\nMit abnehmender Korngr\u00f6\u00dfe steigt die Neigung der<br \/>\nSt\u00e4ube zu Explosionen, d.h. je feiner der Staub, umso<br \/>\nleichter ist er zu entz\u00fcnden, und umso heftiger verl\u00e4uft die Reaktion.<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Z\u00fcndtemperatur [\u00b0C]<\/td><td class=\"column-2\">Unter Versuchsbedingungen ermittelte, niedrigste Temperatur einer hei\u00dfen Oberfl\u00e4che, bei der die Entz\u00fcndungen eines brennbaren Stoffes als Staub-\/Luft- oder Dampf-\/Luft-Gemisch eintritt. Die Z\u00fcndtemperatur einer Staubschicht (Glimmtemperatur) weicht von der Z\u00fcndtemperatur einer Staubwolke ab. Der niedrigere Wert bestimmt die max. zul\u00e4ssige Oberfl\u00e4chentemperatur.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-6 from cache -->\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading h2-blog\" id=\"h-voraussetzungen-fur-eine-explosion\">Prerequisiti per un\u2019esplosione<\/h2>\n\n<figure class=\"wp-block-image size-full img-blog\"><img decoding=\"async\" width=\"600\" height=\"441\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/blog_gefahrenfuenfeck-16b24adb.jpg\" alt=\"Gefahrenfuenfeck\" class=\"wp-image-210295 lazyload\" title=\"ATEX: gli indicatori di esplosione pi\u00f9 importanti in un colpo d'occhio\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/blog_gefahrenfuenfeck-16b24adb.jpg 600w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/blog_gefahrenfuenfeck-16b24adb-480x353.jpg 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 600px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/441;\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Le esplosioni possono essere prevenute. Ci\u00f2 richiede la conoscenza del \u201cpentagono dei pericoli\u201d: questo pentagono rappresenta le cause delle esplosioni in un contesto. \u00c8 sufficiente eliminare uno di questi prerequisiti per evitare un\u2019esplosione.  <\/p>\n\n<div style=\"height:57px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">N\u00b0<\/th><th class=\"column-2\">Voraussetzung<\/th><th class=\"column-3\">Erkl\u00e4rung<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Brennbarer Stoff\/<br \/>\nCombustible substance<\/td><td class=\"column-3\">z.B. in der Produktion anfallender Staub<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Ausreichende Feinheit\/<br \/>\nsufficient degree of finess<\/td><td class=\"column-3\">Je feiner der Staub, umso leichter ist dieser zu entz\u00fcnden. Ist die Korngr\u00f6\u00dfe < 1mm besteht keine Explosionsgefahr. Je kleiner die Korngr\u00f6\u00dfe wird, umso wahrscheinlicher wird eine Explosion (je nach Staubart)<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">Vermischung\/<br \/>\nmixture<\/td><td class=\"column-3\">Je gr\u00f6\u00dfer die Staubdichte in der Luft, umso explosionsf\u00e4higer ist das Gemisch. Hier ist die Konzentration entscheidend: es gibt eine minimale und eine maximale Konzentrationsgrenze, die den Bereich der Explosionsf\u00e4higkeit eingrenzen (ist zu wenig oder zu viel Staub vorhanden, kann keine Explosion stattfinden).<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">Wirksame Z\u00fcndquelle\/<br \/>\neffective source of ignition<\/td><td class=\"column-3\">Die DIN EN 1127 beschreibt verschiedene Z\u00fcndquellen. F\u00fcr die Konstruktion und Anwendung von Entstaubungsanlagen bzw. Filteranlagen sind beispielsweise hei\u00dfe Oberfl\u00e4chen, statische Elektrizit\u00e4t oder mechanisch erzeugte Funken zu nennen.<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">Oxidationsmittel\/<br \/>\nOxidizing agents<\/td><td class=\"column-3\">Oxidationsmittel ist z.B. der Sauerstoff in der Luft. Der Anteil kann durch Inertisierung gesenkt werden, was die Explosionsgefahr eind\u00e4mmt.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-8 from cache -->\n\n<div style=\"height:57px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading h2-blog\" id=\"h-fazit\">Conclusione<\/h2>\n\n<p class=\"wp-block-paragraph\">A seconda del tipo di polvere, il rischio di esplosioni in un impianto di produzione \u00e8 pi\u00f9 o meno elevato. Questo evento deve essere evitato per proteggere il personale, l\u2019impianto e le attrezzature a valle. La conoscenza del tipo di polvere e delle condizioni generali per il verificarsi di un\u2019esplosione sono di fondamentale importanza. Se si sa cosa succede nel processo, il rischio di esplosione pu\u00f2 essere efficacemente eliminato in anticipo.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come si verificano le esplosioni? Cosa comporta? Come si pu\u00f2 valutare il pericolo e infine evitarlo? Queste domande sorgono quando, ad esempio, si possono formare miscele esplosive a causa della presenza di polveri.   <\/p>\n","protected":false},"author":8,"featured_media":235951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[395],"tags":[396,399,400,398,397],"class_list":["post-235989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-protezione-dalle-esplosioni","tag-atex-it","tag-ex-zona-it","tag-tavoli-di-zona-atex","tag-zona-atex-it","tag-zone-atex"],"_links":{"self":[{"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/posts\/235989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/comments?post=235989"}],"version-history":[{"count":1,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/posts\/235989\/revisions"}],"predecessor-version":[{"id":235993,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/posts\/235989\/revisions\/235993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/media\/235951"}],"wp:attachment":[{"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/media?parent=235989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/categories?post=235989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/het-filter.de\/it\/wp-json\/wp\/v2\/tags?post=235989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}