{"id":234119,"date":"2021-12-14T11:26:16","date_gmt":"2021-12-14T10:26:16","guid":{"rendered":"https:\/\/het-filter.de\/elementos-filtrantes-el-corazon-de-los-aspiradores-que-son-y-como-funcionan\/"},"modified":"2024-06-06T14:38:57","modified_gmt":"2024-06-06T12:38:57","slug":"elementos-filtrantes-el-corazon-de-los-aspiradores-que-son-y-como-funcionan","status":"publish","type":"post","link":"https:\/\/het-filter.de\/es\/elementos-filtrantes-el-corazon-de-los-aspiradores-que-son-y-como-funcionan\/","title":{"rendered":"Elementos filtrantes, el coraz\u00f3n de los aspiradores: qu\u00e9 son y c\u00f3mo funcionan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El polvo es un problema recurrente en la producci\u00f3n de las industrias farmac\u00e9utica y qu\u00edmica. Como esto no es deseable, deben tomarse medidas para evitar la aparici\u00f3n de estos polvos. Una posibilidad es utilizar sistemas de filtrado, los llamados extractores de polvo. El polvo se separa del aire y se recoge en estos sistemas.<\/p>\n\n<p class=\"wp-block-paragraph\">Para ello, los sistemas de filtrado est\u00e1n equipados con elementos filtrantes cuyos medios filtrantes o esteras filtrantes atrapan el polvo e impiden que siga siendo transportado con el aire. Hay distintos dise\u00f1os de filtros y distintos materiales de los que pueden estar hechos.<\/p>\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n te explicamos c\u00f3mo funciona el principio de la filtraci\u00f3n para que entiendas lo que es importante a la hora de seleccionar los materiales.<\/p>\n\n<h2 class=\"wp-block-heading h2-blog\">Criterios que influyen en la selecci\u00f3n del filtro<\/h2>\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n del n\u00famero, tipo y materiales de los elementos filtrantes -tambi\u00e9n denominados celdas filtrantes- depende de la naturaleza de la sustancia que se va a filtrar y de las condiciones en las que tiene lugar la filtraci\u00f3n. Deben cumplirse las siguientes condiciones:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Caudal volum\u00e9trico<sup>[m3\/h<\/sup>]:<br>El caudal volum\u00e9trico describe la cantidad de aire que hay que filtrar por hora. Como el elemento filtrante est\u00e1 limitado por su dise\u00f1o, hay que aumentar el n\u00famero de elementos filtrantes a medida que aumenta el caudal volum\u00e9trico.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Composici\u00f3n del medio:<br>Las aplicaciones suelen implicar aire cargado de part\u00edculas. Sin embargo, el medio tambi\u00e9n puede contener otros gases y polvos. La composici\u00f3n del medio que fluye a trav\u00e9s del filtro determina la elecci\u00f3n de los materiales filtrantes, ya que las sustancias deben ser compatibles entre s\u00ed y no deben reaccionar para evitar peligros mayores.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Temperatura del aire [\u00b0C]:<br>La temperatura del aire que fluye a trav\u00e9s de las celdas del filtro, as\u00ed como su composici\u00f3n, determinan los materiales filtrantes. A temperaturas m\u00e1s altas, debe utilizarse material resistente al calor para evitar un desgaste prematuro o incluso la destrucci\u00f3n de la c\u00e9lula filtrante.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Carga de polvo en el aire <sup>[mg\/m3<\/sup>]:<br>La carga de polvo indica cu\u00e1nto polvo o cu\u00e1ntas part\u00edculas hay en el aire que hay que filtrar. Esta cantidad determina el tipo de filtro. Un elemento filtrante s\u00f3lo tiene una determinada vida \u00fatil, es decir, s\u00f3lo puede absorber polvo hasta que se obstruye. Cuantas m\u00e1s part\u00edculas haya en el aire, m\u00e1s r\u00e1pidamente se obstruye el filtro y se alcanza su l\u00edmite de funcionamiento. Dependiendo del tipo de filtro, \u00e9ste se puede limpiar y, por tanto, est\u00e1 listo para volver a utilizarse o -si esto no es posible- hay que sustituirlo.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li>Requisitos del proceso:<br>Del proceso surgen las siguientes preguntas:<br>\u2013 \u00bfQu\u00e9 debe hacerse con el material separado?<br>\u2013 \u00bfDebe simplemente separarse o debe reutilizarse?<br>\u2013 \u00bfC\u00f3mo debe funcionar el sistema de filtrado? \u00bfSon los tiempos de inactividad debidos a actividades de servicio en<br>\u2013 \u00bfes posible el proceso o debe funcionar continuamente el sistema de filtrado?<br>\u2013 \u00bfExisten normativas que deban cumplirse debido a las aplicaciones, por ejemplo, ATEX?<br>\u2013 \u00bfHay alg\u00fan requisito relativo a la contenci\u00f3n?<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Las respuestas son importantes para la selecci\u00f3n de los elementos filtrantes, porque determinan la capacidad de limpieza y el n\u00famero de filtros o el tipo de dise\u00f1o.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Si hay que reciclar sustancias, la c\u00e9lula filtrante debe poder limpiarse. Si no es as\u00ed, la sustancia permanece en el medio filtrante y se elimina junto con la c\u00e9lula filtrante.<\/li>\n\n\n\n<li>Si el sistema de filtrado se va a utilizar de forma continua, hay que prever filtros adicionales para que el caudal volum\u00e9trico se distribuya en consecuencia durante la limpieza (la filtraci\u00f3n en el filtro no es posible durante la limpieza, por lo que el caudal volum\u00e9trico se distribuye a los dem\u00e1s filtros).<\/li>\n\n\n\n<li>Si hay una atm\u00f3sfera explosiva y existe riesgo de explosi\u00f3n, la c\u00e9lula filtrante y sus componentes deben conectarse a tierra para evitar efectos electrost\u00e1ticos.<\/li>\n\n\n\n<li>Si existen requisitos relativos a la pureza del aire, deben respetarse los grupos de filtros seg\u00fan las clases de filtros<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading h3-blog\">Estructura y modo de funcionamiento de una c\u00e9lula filtrante<\/h3>\n\n<p class=\"wp-block-paragraph\">Para comprender mejor la influencia de estos criterios, hay que conocer el principio de funcionamiento de los elementos filtrantes.<\/p>\n\n<p class=\"wp-block-paragraph\">El polvo, o m\u00e1s bien las distintas part\u00edculas que contiene, tienen distintas propiedades que son decisivas para la eficacia de la filtraci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de estas propiedades del polvo en s\u00ed -el polvo pegajoso, por ejemplo, hace que el medio filtrante se atasque m\u00e1s r\u00e1pidamente, mientras que el polvo que fluye libremente es muy f\u00e1cil de filtrar-, tambi\u00e9n hay que tener en cuenta las propiedades de las part\u00edculas individuales y de la c\u00e9lula filtrante.<\/p>\n\n<h4 class=\"wp-block-heading h3-blog\">Estructura de la c\u00e9lula filtrante<\/h4>\n\n<figure class=\"wp-block-image size-full img-blog\"><img decoding=\"async\" width=\"1039\" height=\"605\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Filterzelle_Aufbau_bearb.jpg\" alt=\"Estructura de la c\u00e9lula filtrante\" class=\"wp-image-210260 lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Filterzelle_Aufbau_bearb.jpg 1039w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Filterzelle_Aufbau_bearb-980x571.jpg 980w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Filterzelle_Aufbau_bearb-480x279.jpg 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1039px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1039px; --smush-placeholder-aspect-ratio: 1039\/605;\" \/><figcaption class=\"wp-element-caption\">Estructura de una c\u00e9lula filtrante<\/figcaption><\/figure>\n\n<ol class=\"wp-block-list\">\n<li>Medio filtrante<\/li>\n\n\n\n<li>Espaciador<\/li>\n\n\n\n<li>Encapsulado<\/li>\n\n\n\n<li>Junta<\/li>\n\n\n\n<li>Armaz\u00f3n de metal<\/li>\n<\/ol>\n\n<div style=\"height:67px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Efectos de la filtraci\u00f3n<\/h2>\n\n<p class=\"wp-block-paragraph\">Para explicar el principio de la filtraci\u00f3n, es decir, la separaci\u00f3n mec\u00e1nica de las sustancias de los gases, es necesario pasar de la c\u00e9lula filtrante en su conjunto a la fibra filtrante en particular: aqu\u00ed act\u00faan a peque\u00f1a escala efectos f\u00edsicos que son importantes para el resultado a gran escala.<br>Las part\u00edculas que atraviesan la c\u00e9lula filtrante siguen el flujo de aire. El tama\u00f1o y la naturaleza de estas part\u00edculas determinan lo que ocurre dentro de la c\u00e9lula filtrante, en las fibras filtrantes.<\/p>\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Efecto de inercia:<\/strong><br>una part\u00edcula de <strong>gran<\/strong> masa es relativamente inerte. Si el aire pasa por delante de la fibra filtrante, esta part\u00edcula no puede seguirla, choca contra la fibra y se pega a ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"971\" height=\"441\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Traegheitseffekt.png\" alt=\"Efecto de inercia\" class=\"wp-image-210268 size-full lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Traegheitseffekt.png 971w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Traegheitseffekt-480x218.png 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 971px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 971px; --smush-placeholder-aspect-ratio: 971\/441;\" \/><\/figure><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Difusi\u00f3n<\/strong><br>Una part\u00edcula de tama\u00f1o <strong>muy<\/strong> peque\u00f1o fluye con la corriente de aire, pero no sigue las l\u00edneas de corriente, sino que se desv\u00eda de ellas. Durante estos movimientos, puede golpear una fibra u otras part\u00edculas y adherirse a ellas. La causa de este comportamiento difuso reside en el movimiento molecular browniano.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"971\" height=\"440\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diffusion.png\" alt=\"Difusi\u00f3n\" class=\"wp-image-210271 size-full lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diffusion.png 971w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diffusion-480x218.png 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 971px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 971px; --smush-placeholder-aspect-ratio: 971\/440;\" \/><\/figure><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Efecto de bloqueo:<\/strong><br>Una part\u00edcula <strong>grande<\/strong>sigue el flujo de aire en las l\u00edneas de corriente, pero es demasiado grande para evitar las fibras del filtro. Debido a sus dimensiones, golpea la fibra filtrante al fluir a su alrededor y se pega a ella.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"972\" height=\"441\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Sperreffekt.png\" alt=\"Efecto de bloqueo\" class=\"wp-image-210273 size-full lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Sperreffekt.png 972w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Sperreffekt-480x218.png 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 972px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 972px; --smush-placeholder-aspect-ratio: 972\/441;\" \/><\/figure><\/div>\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>Atracci\u00f3n electrost\u00e1tica  <br>(fuerzas de Van der Waals):<\/strong><br>El movimiento y la fricci\u00f3n asociada de las part\u00edculas pueden hacer que \u00e9stas y la fibra filtrante se <strong>carguen electrost\u00e1ticamente<\/strong>. Si la carga es opuesta en cada caso, la part\u00edcula es atra\u00edda por la fibra filtrante y se adhiere a ella.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"971\" height=\"440\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Elektrostatik.png\" alt=\"\" class=\"wp-image-210276 size-full lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Elektrostatik.png 971w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Elektrostatik-480x218.png 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 971px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 971px; --smush-placeholder-aspect-ratio: 971\/440;\" \/><\/figure><\/div>\n\n<div style=\"height:71px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Estos efectos garantizan que las part\u00edculas del aire queden retenidas en el medio de la c\u00e9lula filtrante. Lo bien que funciona esto lo indica la eficacia, tambi\u00e9n conocida como eficiencia de separaci\u00f3n. Indica cu\u00e1ntas part\u00edculas quedan en la c\u00e9lula filtrante o cu\u00e1ntas part\u00edculas quedan en el aire de escape despu\u00e9s de pasar por la c\u00e9lula filtrante. La eficacia de separaci\u00f3n se especifica en porcentaje (n\u00famero de part\u00edculas separadas en relaci\u00f3n con las part\u00edculas entrantes).<br>  La influencia de los distintos efectos en la eficacia de la separaci\u00f3n se muestra en el diagrama siguiente:<\/p>\n\n<figure class=\"wp-block-image size-full img-blog\"><img decoding=\"async\" width=\"600\" height=\"375\" data-src=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diagram_A-PM-dd094909.png\" alt=\"\" class=\"wp-image-210281 lazyload\" data-srcset=\"https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diagram_A-PM-dd094909.png 600w, https:\/\/het-filter.de\/wp-content\/uploads\/2022\/10\/Diagram_A-PM-dd094909-480x300.png 480w\" data-sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 600px, 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/375;\" \/><\/figure>\n\n<ul class=\"wp-block-list\">\n<li>Difusi\u00f3n A Grado de separaci\u00f3n [%]<\/li>\n\n\n\n<li>Efecto de bloqueo PM Tama\u00f1o de las part\u00edculas [\u00b5m]<\/li>\n\n\n\n<li>Efecto inercia MPPS part\u00edculas 0,1-0,3 \u00b5m -&gt; filtraci\u00f3n m\u00ednima<\/li>\n<\/ul>\n\n<div style=\"height:58px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p class=\"wp-block-paragraph\">Como en el aire hay part\u00edculas de distintos tama\u00f1os y propiedades, los efectos mencionados act\u00faan de distintas maneras. Las part\u00edculas m\u00e1s peque\u00f1as se separan debido a la difusi\u00f3n. Las part\u00edculas m\u00e1s grandes permanecen en el medio filtrante debido al efecto de inercia o de bloqueo. En medio, hay efectos superpuestos que influyen en la eficacia de filtraci\u00f3n de la c\u00e9lula filtrante.<\/p>\n\n<p class=\"wp-block-paragraph\">El diagrama ejemplar muestra claramente que hay un m\u00ednimo de filtraci\u00f3n a un determinado tama\u00f1o de part\u00edcula. Este punto bajo se denomina \u00abMPPS = Tama\u00f1o de part\u00edcula de mayor penetraci\u00f3n\u00bb. Esta gama est\u00e1 disponible para tama\u00f1os de part\u00edcula entre 0,1 \u00b5m y 0,3 \u00b5m y cubre el rendimiento de filtraci\u00f3n de las part\u00edculas que la experiencia ha demostrado que son las m\u00e1s dif\u00edciles de filtrar. La c\u00e9lula filtrante se clasifica en funci\u00f3n de la eficacia de separaci\u00f3n en este punto. Al clasificar la c\u00e9lula filtrante en distintos niveles o clases en funci\u00f3n de distintas normas, la c\u00e9lula filtrante puede describirse en consecuencia, de modo que pueda compararse con los requisitos de contenci\u00f3n del proceso.<\/p>\n\n<h2 class=\"wp-block-heading h2-blog\">Conclusi\u00f3n<\/h2>\n\n<p class=\"wp-block-paragraph\">El conocimiento de las condiciones reinantes y de las propiedades del polvo que se produce desempe\u00f1a un papel muy importante en la planificaci\u00f3n y el dise\u00f1o de los sistemas de filtrado y, sobre todo, de los elementos filtrantes. De ello se derivan los requisitos que debe cumplir una c\u00e9lula filtrante del sistema de filtrado para producir aire de escape de la calidad deseada. Con este conocimiento, se puede determinar la c\u00e9lula filtrante que mejor se adapte al proceso a partir de la gran cantidad de c\u00e9lulas filtrantes disponibles. Es fundamental hablar con los ingenieros del fabricante, ya que ellos tienen la experiencia necesaria para dise\u00f1ar y seleccionar los componentes adecuados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El polvo es un problema recurrente en la producci\u00f3n de las industrias farmac\u00e9utica y qu\u00edmica. Como esto no es deseable, deben tomarse medidas para evitar la aparici\u00f3n de estos polvos. Una posibilidad es utilizar sistemas de filtrado, los llamados extractores de polvo. El polvo se separa del aire y se recoge en estos sistemas. Para [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":234130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[139],"tags":[153,152,155,154,156],"class_list":["post-234119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filtros","tag-gmp-es","tag-industria-farmaceutica","tag-sala-blanca","tag-sistemas-de-filtrado","tag-tecnologia-de-salas-blancas"],"_links":{"self":[{"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/posts\/234119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/comments?post=234119"}],"version-history":[{"count":0,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/posts\/234119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/media\/234130"}],"wp:attachment":[{"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/media?parent=234119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/categories?post=234119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/het-filter.de\/es\/wp-json\/wp\/v2\/tags?post=234119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}